{"id":2270,"date":"2026-05-21T08:13:06","date_gmt":"2026-05-21T08:13:06","guid":{"rendered":"https:\/\/www.activespacetech.com\/a-active-space-technologies-e-destaque-num-artigo-sobre-o-ecossistema-espacial-de-coimbra\/"},"modified":"2026-06-16T08:13:06","modified_gmt":"2026-06-16T08:13:06","slug":"a-active-space-technologies-e-destaque-num-artigo-sobre-o-ecossistema-espacial-de-coimbra","status":"publish","type":"post","link":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/a-active-space-technologies-e-destaque-num-artigo-sobre-o-ecossistema-espacial-de-coimbra\/","title":{"rendered":"A Active Space Technologies \u00e9 destaque num artigo sobre o ecossistema espacial de Coimbra"},"content":{"rendered":"<p>A Active Space Technologies \u00e9 destaque num artigo recente da The Next Big Idea, que destaca o papel crescente de Coimbra na economia espacial, na v\u00e9spera da Startup Capital Summit.<br \/>Com mais de duas d\u00e9cadas de atividade, a AST contribui para v\u00e1rios programas espaciais, acumulando uma vasta experi\u00eancia em engenharia e integrando cadeias de abastecimento internacionais, como parte de um ecossistema mais amplo que promove a colabora\u00e7\u00e3o e a inova\u00e7\u00e3o na regi\u00e3o.<\/p>\n<p><a href=\"https:\/\/thenextbigidea.pt\/o-espaco-ja-nao-e-so-para-os-grandes-e-coimbra-quer-ser-o-polo-portugues\/\">L\u00ea mais aqui<\/a><\/p>\n<p>Cr\u00e9dito da imagem: The Next Big Idea<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Active Space Technologies \u00e9 destaque num artigo recente da The Next Big Idea, que destaca o papel crescente de Coimbra na economia espacial, na v\u00e9spera da Startup Capital Summit.Com mais de duas d\u00e9cadas de atividade, a AST contribui para v\u00e1rios programas espaciais, acumulando uma vasta experi\u00eancia em engenharia e integrando cadeias de abastecimento internacionais, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2269,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-2270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hover-yellow"],"acf":[],"_links":{"self":[{"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/posts\/2270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/comments?post=2270"}],"version-history":[{"count":0,"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/posts\/2270\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/media\/2269"}],"wp:attachment":[{"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/media?parent=2270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/categories?post=2270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/tags?post=2270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}