{"id":1404,"date":"2025-10-09T16:32:25","date_gmt":"2025-10-09T16:32:25","guid":{"rendered":"https:\/\/activespace.nxsoft.pt\/active-space-technologies-at-inovacaouc\/"},"modified":"2025-12-30T16:56:21","modified_gmt":"2025-12-30T16:56:21","slug":"active-space-technologies-at-inovacaouc","status":"publish","type":"post","link":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/active-space-technologies-at-inovacaouc\/","title":{"rendered":"Active Space Technologies at Inova\u00e7\u00e3o@UC"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br>A Active Space Technologies participou no Inova\u00e7\u00e3o@UC 2025, um evento organizado pela Universidade de Coimbra dedicado \u00e0 inova\u00e7\u00e3o e investiga\u00e7\u00e3o aplicada. A<sup>5\u00aa<\/sup> edi\u00e7\u00e3o destacou temas como o Espa\u00e7o, a Computa\u00e7\u00e3o Qu\u00e2ntica, os Materiais Avan\u00e7ados e a Sustentabilidade, apresentando projectos que demonstram como o desenvolvimento cient\u00edfico e tecnol\u00f3gico pode criar impacto em m\u00faltiplos sectores. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Active Space Technologies participou no Inova\u00e7\u00e3o@UC 2025, um evento organizado pela Universidade de Coimbra dedicado \u00e0 inova\u00e7\u00e3o e investiga\u00e7\u00e3o aplicada. A5\u00aa edi\u00e7\u00e3o destacou temas como o Espa\u00e7o, a Computa\u00e7\u00e3o Qu\u00e2ntica, os Materiais Avan\u00e7ados e a Sustentabilidade, apresentando projectos que demonstram como o desenvolvimento cient\u00edfico e tecnol\u00f3gico pode criar impacto em m\u00faltiplos sectores.<\/p>\n","protected":false},"author":2,"featured_media":1405,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-1404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hover-yellow"],"acf":[],"_links":{"self":[{"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/posts\/1404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/comments?post=1404"}],"version-history":[{"count":2,"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/posts\/1404\/revisions"}],"predecessor-version":[{"id":1603,"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/posts\/1404\/revisions\/1603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/media\/1405"}],"wp:attachment":[{"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/media?parent=1404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/categories?post=1404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quizzical-ishizaka.109-199-104-68.plesk.page\/pt-pt\/wp-json\/wp\/v2\/tags?post=1404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}